{"id":1756,"count":12,"description":"","link":"https:\/\/saudimedicalstore.com\/en\/brand\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\/","name":"BTL-BTL","slug":"btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84","taxonomy":"pwb-brand","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>BTL- \u0628\u064a \u062a\u064a \u0627\u0644 \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a \u0627\u0644\u0633\u0639\u0648\u062f\u064a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saudimedicalstore.com\/en\/brand\/btl-\u0628\u064a-\u062a\u064a-\u0627\u0644\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BTL- \u0628\u064a \u062a\u064a \u0627\u0644 \u0627\u0644\u0623\u0631\u0634\u064a\u0641\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saudimedicalstore.com\/en\/brand\/btl-\u0628\u064a-\u062a\u064a-\u0627\u0644\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a \u0627\u0644\u0633\u0639\u0648\u062f\u064a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@saudi_m_store\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/saudimedicalstore.com\\\/brand\\\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\\\/\",\"url\":\"https:\\\/\\\/saudimedicalstore.com\\\/brand\\\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\\\/\",\"name\":\"BTL- \u0628\u064a \u062a\u064a \u0627\u0644 \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a \u0627\u0644\u0633\u0639\u0648\u062f\u064a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saudimedicalstore.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/saudimedicalstore.com\\\/brand\\\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/saudimedicalstore.com\\\/brand\\\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\\\/\\\/saudimedicalstore.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BTL- \u0628\u064a \u062a\u064a \u0627\u0644\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/saudimedicalstore.com\\\/#website\",\"url\":\"https:\\\/\\\/saudimedicalstore.com\\\/\",\"name\":\"\u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a \u0627\u0644\u0633\u0639\u0648\u062f\u064a\",\"description\":\"\u0645\u062a\u062c\u0631 \u0633\u0639\u0648\u062f\u0649 \u0645\u062e\u062a\u0635 \u0641\u0649 \u0628\u064a\u0639 \u0648\u062a\u0648\u0632\u064a\u0639 \u0627\u0644\u0645\u0633\u062a\u0644\u0632\u0645\u0627\u062a \u0648\u0627\u0644\u0645\u0639\u062f\u0627\u062a \u0627\u0644\u0637\u0628\u064a\u0629 \u0648\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0648\u0627\u0644\u062c\u0645\u0627\u0644 \u0648\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u0639\u0644\u0627\u062c \u0627\u0644\u0637\u0628\u064a\u0639\u064a \u0648\u062a\u0648\u0631\u064a\u062f \u0648\u062a\u062c\u0647\u064a\u0632 \u0627\u0644\u0645\u0633\u062a\u0634\u0641\u064a\u0627\u062a \u0648\u0645\u0631\u0627\u0643\u0632 \u0627\u0644\u0639\u0644\u0627\u062c \u0627\u0644\u0637\u0628\u064a\u0639\u064a \u0628\u0627\u0641\u0636\u0644 \u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0628\u0627\u0633\u0639\u0627\u0631 \u0645\u0646\u0627\u0641\u0633\u0629 \u062c\u062f\u0627\",\"publisher\":{\"@id\":\"https:\\\/\\\/saudimedicalstore.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/saudimedicalstore.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\",\"Corporation\"],\"@id\":\"https:\\\/\\\/saudimedicalstore.com\\\/#organization\",\"name\":\"\u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a \u0627\u0644\u0633\u0639\u0648\u062f\u064a\",\"alternateName\":\"\u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a\",\"url\":\"https:\\\/\\\/saudimedicalstore.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/saudimedicalstore.com\\\/brand\\\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/saudimedicalstore.com\\\/brand\\\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/saudimedicalstore1\\\/\",\"https:\\\/\\\/x.com\\\/saudi_m_store\",\"https:\\\/\\\/www.instagram.com\\\/saudi_m_store\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@saudimedicalstore\",\"https:\\\/\\\/www.snapchat.com\\\/add\\\/smedical.store\",\"https:\\\/\\\/www.tiktok.com\\\/@saudi_m_store\"],\"description\":\"\u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a \u0627\u0644\u0633\u0639\u0648\u062f\u064a \u0647\u0648 \u0645\u062a\u062c\u0631 \u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a \u0645\u062a\u062e\u0635\u0635 \u0641\u064a \u0628\u064a\u0639 \u0627\u0644\u0623\u062c\u0647\u0632\u0629 \u0648\u0627\u0644\u0645\u0633\u062a\u0644\u0632\u0645\u0627\u062a \u0627\u0644\u0637\u0628\u064a\u0629 \u0627\u0644\u0623\u0635\u0644\u064a\u0629 \u062f\u0627\u062e\u0644 \u0627\u0644\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0627\u0644\u0633\u0639\u0648\u062f\u064a\u0629.\",\"legalName\":\"\u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a \u0627\u0644\u0633\u0639\u0648\u062f\u064a\",\"foundingDate\":\"2024-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"ownershipFundingInfo\":\"https:\\\/\\\/saudimedicalstore.com\\\/%d9%85%d9%86-%d9%86%d8%ad%d9%861\\\/\",\"ethicsPolicy\":\"https:\\\/\\\/saudimedicalstore.com\\\/%d8%a7%d9%84%d8%b4%d8%b1%d9%88%d8%b7-%d9%88%d8%a7%d9%84%d8%a3%d8%ad%d9%83%d8%a7%d9%85\\\/\",\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/saudimedicalstore.com\\\/en\\\/%d8%b3%d9%8a%d8%a7%d8%b3%d8%a9-%d8%a7%d9%84%d8%a7%d8%b3%d8%aa%d8%a8%d8%af%d8%a7%d9%84-%d9%88-%d8%a7%d9%84%d8%a7%d8%b3%d8%aa%d8%b1%d8%ac%d8%a7%d8%b9\\\/\"},\"address\":{\"@id\":\"https:\\\/\\\/saudimedicalstore.com\\\/brand\\\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\\\/#local-main-place-address\"},\"telephone\":[\"0576262190\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"0576262190\",\"email\":\"info@saudimedicalstore.com\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Saturday\",\"Sunday\",\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\"],\"opens\":\"09:30\",\"closes\":\"23:00\"},{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Friday\"],\"opens\":\"15:30\",\"closes\":\"23:00\"}],\"email\":\"info@saudimedicalstore.com\",\"vatID\":\"314063845400003\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/saudimedicalstore.com\\\/brand\\\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\\\/#local-main-place-address\",\"streetAddress\":\"\u062d\u0649 \u0627\u0644\u0639\u0632\u064a\u0632\u0647 \u0634\u0627\u0631\u0639 \u0627\u0644\u0634\u0628\u0627\u0628\",\"addressLocality\":\"\u0627\u0644\u0631\u064a\u0627\u0636\",\"postalCode\":\"14512\",\"addressRegion\":\"\u0627\u0644\u0631\u064a\u0627\u0636\",\"addressCountry\":\"SA\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/saudimedicalstore.com\\\/brand\\\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/saudimedicalstore.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/\u0644\u0648\u062c\u0648-600.png\",\"contentUrl\":\"https:\\\/\\\/saudimedicalstore.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/\u0644\u0648\u062c\u0648-600.png\",\"width\":600,\"height\":600,\"caption\":\"\u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a \u0627\u0644\u0633\u0639\u0648\u062f\u064a\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"\u0627\u0644\u0631\u064a\u0627\u0636\" \/>\n<meta name=\"geo.region\" content=\"Saudi Arabia\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"BTL- \u0628\u064a \u062a\u064a \u0627\u0644 \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a \u0627\u0644\u0633\u0639\u0648\u062f\u064a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/saudimedicalstore.com\/en\/brand\/btl-\u0628\u064a-\u062a\u064a-\u0627\u0644\/","og_locale":"en_US","og_type":"article","og_title":"BTL- \u0628\u064a \u062a\u064a \u0627\u0644 \u0627\u0644\u0623\u0631\u0634\u064a\u0641","og_url":"https:\/\/saudimedicalstore.com\/en\/brand\/btl-\u0628\u064a-\u062a\u064a-\u0627\u0644\/","og_site_name":"\u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a \u0627\u0644\u0633\u0639\u0648\u062f\u064a","twitter_card":"summary_large_image","twitter_site":"@saudi_m_store","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/saudimedicalstore.com\/brand\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\/","url":"https:\/\/saudimedicalstore.com\/brand\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\/","name":"BTL- \u0628\u064a \u062a\u064a \u0627\u0644 \u0627\u0644\u0623\u0631\u0634\u064a\u0641 - \u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a \u0627\u0644\u0633\u0639\u0648\u062f\u064a","isPartOf":{"@id":"https:\/\/saudimedicalstore.com\/#website"},"breadcrumb":{"@id":"https:\/\/saudimedicalstore.com\/brand\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/saudimedicalstore.com\/brand\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/saudimedicalstore.com\/"},{"@type":"ListItem","position":2,"name":"BTL- \u0628\u064a \u062a\u064a \u0627\u0644"}]},{"@type":"WebSite","@id":"https:\/\/saudimedicalstore.com\/#website","url":"https:\/\/saudimedicalstore.com\/","name":"Saudi medical store","description":"A Saudi store specialized in selling and distributing medical supplies and equipment, care and beauty products, physical therapy products, and supplying and equipping hospitals and physical therapy centers with the best products at very competitive prices.","publisher":{"@id":"https:\/\/saudimedicalstore.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/saudimedicalstore.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place","Corporation"],"@id":"https:\/\/saudimedicalstore.com\/#organization","name":"Saudi medical store","alternateName":"\u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a","url":"https:\/\/saudimedicalstore.com\/","logo":{"@id":"https:\/\/saudimedicalstore.com\/brand\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\/#local-main-organization-logo"},"image":{"@id":"https:\/\/saudimedicalstore.com\/brand\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/saudimedicalstore1\/","https:\/\/x.com\/saudi_m_store","https:\/\/www.instagram.com\/saudi_m_store\/","https:\/\/www.youtube.com\/@saudimedicalstore","https:\/\/www.snapchat.com\/add\/smedical.store","https:\/\/www.tiktok.com\/@saudi_m_store"],"description":"\u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a \u0627\u0644\u0633\u0639\u0648\u062f\u064a \u0647\u0648 \u0645\u062a\u062c\u0631 \u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a \u0645\u062a\u062e\u0635\u0635 \u0641\u064a \u0628\u064a\u0639 \u0627\u0644\u0623\u062c\u0647\u0632\u0629 \u0648\u0627\u0644\u0645\u0633\u062a\u0644\u0632\u0645\u0627\u062a \u0627\u0644\u0637\u0628\u064a\u0629 \u0627\u0644\u0623\u0635\u0644\u064a\u0629 \u062f\u0627\u062e\u0644 \u0627\u0644\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0627\u0644\u0633\u0639\u0648\u062f\u064a\u0629.","legalName":"\u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a \u0627\u0644\u0633\u0639\u0648\u062f\u064a","foundingDate":"2024-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"ownershipFundingInfo":"https:\/\/saudimedicalstore.com\/%d9%85%d9%86-%d9%86%d8%ad%d9%861\/","ethicsPolicy":"https:\/\/saudimedicalstore.com\/%d8%a7%d9%84%d8%b4%d8%b1%d9%88%d8%b7-%d9%88%d8%a7%d9%84%d8%a3%d8%ad%d9%83%d8%a7%d9%85\/","hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/saudimedicalstore.com\/en\/%d8%b3%d9%8a%d8%a7%d8%b3%d8%a9-%d8%a7%d9%84%d8%a7%d8%b3%d8%aa%d8%a8%d8%af%d8%a7%d9%84-%d9%88-%d8%a7%d9%84%d8%a7%d8%b3%d8%aa%d8%b1%d8%ac%d8%a7%d8%b9\/"},"address":{"@id":"https:\/\/saudimedicalstore.com\/brand\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\/#local-main-place-address"},"telephone":["0576262190"],"contactPoint":{"@type":"ContactPoint","telephone":"0576262190","email":"info@saudimedicalstore.com"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Saturday","Sunday","Monday","Tuesday","Wednesday","Thursday"],"opens":"09:30","closes":"23:00"},{"@type":"OpeningHoursSpecification","dayOfWeek":["Friday"],"opens":"15:30","closes":"23:00"}],"email":"info@saudimedicalstore.com","vatID":"314063845400003"},{"@type":"PostalAddress","@id":"https:\/\/saudimedicalstore.com\/brand\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\/#local-main-place-address","streetAddress":"\u062d\u0649 \u0627\u0644\u0639\u0632\u064a\u0632\u0647 \u0634\u0627\u0631\u0639 \u0627\u0644\u0634\u0628\u0627\u0628","addressLocality":"\u0627\u0644\u0631\u064a\u0627\u0636","postalCode":"14512","addressRegion":"\u0627\u0644\u0631\u064a\u0627\u0636","addressCountry":"SA"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/saudimedicalstore.com\/brand\/btl-%d8%a8%d9%8a-%d8%aa%d9%8a-%d8%a7%d9%84\/#local-main-organization-logo","url":"https:\/\/saudimedicalstore.com\/wp-content\/uploads\/2025\/04\/\u0644\u0648\u062c\u0648-600.png","contentUrl":"https:\/\/saudimedicalstore.com\/wp-content\/uploads\/2025\/04\/\u0644\u0648\u062c\u0648-600.png","width":600,"height":600,"caption":"\u0627\u0644\u0645\u062a\u062c\u0631 \u0627\u0644\u0637\u0628\u064a \u0627\u0644\u0633\u0639\u0648\u062f\u064a"}]},"geo.placename":"\u0627\u0644\u0631\u064a\u0627\u0636","geo.region":"Saudi Arabia"},"_links":{"self":[{"href":"https:\/\/saudimedicalstore.com\/en\/wp-json\/wp\/v2\/pwb-brand\/1756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saudimedicalstore.com\/en\/wp-json\/wp\/v2\/pwb-brand"}],"about":[{"href":"https:\/\/saudimedicalstore.com\/en\/wp-json\/wp\/v2\/taxonomies\/pwb-brand"}],"wp:post_type":[{"href":"https:\/\/saudimedicalstore.com\/en\/wp-json\/wp\/v2\/product?pwb-brand=1756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}